{"id":1,"count":302,"description":"","link":"http:\/\/www.totalbalance.biz\/mugegawa\/category\/%e6%9c%aa%e5%88%86%e9%a1%9e\/","name":"\u672a\u5206\u985e","slug":"%e6%9c%aa%e5%88%86%e9%a1%9e","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.totalbalance.biz\/mugegawa\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"http:\/\/www.totalbalance.biz\/mugegawa\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.totalbalance.biz\/mugegawa\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.totalbalance.biz\/mugegawa\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}